{"id":12169,"date":"2021-09-17T15:08:25","date_gmt":"2021-09-17T13:08:25","guid":{"rendered":"https:\/\/officinegullo.com\/accessori\/parrilla-para-horno-de-acero-inox-2\/"},"modified":"2021-09-17T15:08:25","modified_gmt":"2021-09-17T13:08:25","slug":"parrilla-para-horno-de-acero-inox-2","status":"publish","type":"accessori","link":"https:\/\/officinegullo.com\/es\/accesorios\/accesorios-de-coccion-og-professional\/parrilla-para-horno-de-acero-inox-gn-1-1\/","title":{"rendered":"Parrilla para horno de acero inox gn 1\/1"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":5648,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-12169","accessori","type-accessori","status-publish","has-post-thumbnail","hentry","cat_accessori-accesorios-de-coccion-og-professional","attr_accessori-bandejas"],"acf":{"hreflang":"<link rel=\"alternate\" hreflang=\"en-us\" href=\"https:\/\/us.officinegullo.com\/accessories\/og-professional-cooking-accessories\/stainless-steel-oven-grill-2\/\">\n<link rel=\"alternate\" hreflang=\"fr-ca\" href=\"https:\/\/us.officinegullo.com\/fr-ca\/accessoires\/accessoires-cuisson-og-professional\/grille-pour-four-en-acier-inox-2\/\">\n<link rel=\"alternate\" hreflang=\"ru\" href=\"https:\/\/ru.officinegullo.com\/accessories\/og-professional-cooking-accessories\/stainless-steel-oven-grill-2\/\">\n<link rel=\"alternate\" hreflang=\"zh\" href=\"http:\/\/officinegullo.cn\/accessories\/og-professional-cooking-accessories\/stainless-steel-oven-grill-2\/\">","heading":{"tipo_header":"img","titolo":"Parrilla para horno de acero inox gn 1\/1","codice":"4A023160003A","testo":"Parrilla para horno de acero inox, GN 1\/1 - 53 \u00d7 32,5 cm","finiture":null,"immagine":5648,"galleria":[],"variazioni":null},"contenuto":"fisso","gruppo_fisso":{"":null,"tipo_media_descrizione":"img","testo_descrizione":"","immagine_descrizione":"","gallery_descrizione":null,"layout":"","colonna_1":"","colonna_2":"","colonna_3":"","colonna_4":"","dati_tecnici":null,"gallery":[],"item":"ACCFORNI","variants":"","forcedvariants":"_ACCFORNI=ACC043;","model":"XM0","adds":""},"gruppo_tab":{"tabs":null},"accessori":{"visibile":"no","titolo":"","cta":"","accessories":null},"correlati":{"titolo":"","cta":"","related":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Parrilla para horno de acero inox gn 1\/1 - Officine Gullo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/officinegullo.com\/es\/accesorios\/accesorios-de-coccion-og-professional\/parrilla-para-horno-de-acero-inox-gn-1-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parrilla para horno de acero inox gn 1\/1 - Officine Gullo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/officinegullo.com\/es\/accesorios\/accesorios-de-coccion-og-professional\/parrilla-para-horno-de-acero-inox-gn-1-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Officine Gullo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/s3.eu-central-1.amazonaws.com\/eu.officinegullo.com\/wp-content\/uploads\/2021\/08\/20150528\/ACC043.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/officinegullo.com\\\/es\\\/accesorios\\\/accesorios-de-coccion-og-professional\\\/parrilla-para-horno-de-acero-inox-gn-1-1\\\/\",\"url\":\"https:\\\/\\\/officinegullo.com\\\/es\\\/accesorios\\\/accesorios-de-coccion-og-professional\\\/parrilla-para-horno-de-acero-inox-gn-1-1\\\/\",\"name\":\"Parrilla para horno de acero inox gn 1\\\/1 - Officine Gullo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/officinegullo.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/officinegullo.com\\\/es\\\/accesorios\\\/accesorios-de-coccion-og-professional\\\/parrilla-para-horno-de-acero-inox-gn-1-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/officinegullo.com\\\/es\\\/accesorios\\\/accesorios-de-coccion-og-professional\\\/parrilla-para-horno-de-acero-inox-gn-1-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/s3.eu-central-1.amazonaws.com\\\/eu.officinegullo.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/20150528\\\/ACC043.jpg\",\"datePublished\":\"2021-09-17T13:08:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/officinegullo.com\\\/es\\\/accesorios\\\/accesorios-de-coccion-og-professional\\\/parrilla-para-horno-de-acero-inox-gn-1-1\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/officinegullo.com\\\/es\\\/accesorios\\\/accesorios-de-coccion-og-professional\\\/parrilla-para-horno-de-acero-inox-gn-1-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/officinegullo.com\\\/es\\\/accesorios\\\/accesorios-de-coccion-og-professional\\\/parrilla-para-horno-de-acero-inox-gn-1-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/s3.eu-central-1.amazonaws.com\\\/eu.officinegullo.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/20150528\\\/ACC043.jpg\",\"contentUrl\":\"https:\\\/\\\/s3.eu-central-1.amazonaws.com\\\/eu.officinegullo.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/20150528\\\/ACC043.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/officinegullo.com\\\/es\\\/accesorios\\\/accesorios-de-coccion-og-professional\\\/parrilla-para-horno-de-acero-inox-gn-1-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/officinegullo.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accesorios\",\"item\":\"https:\\\/\\\/officinegullo.com\\\/es\\\/accesorios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Accesorios de cocci\u00f3n OG Professional\",\"item\":\"https:\\\/\\\/officinegullo.com\\\/es\\\/accesorios\\\/accesorios-de-coccion-og-professional\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Parrilla para horno de acero inox gn 1\\\/1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/officinegullo.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/officinegullo.com\\\/es\\\/\",\"name\":\"Officine Gullo\",\"description\":\"The quintessential kitchen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/officinegullo.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Parrilla para horno de acero inox gn 1\/1 - Officine Gullo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/officinegullo.com\/es\/accesorios\/accesorios-de-coccion-og-professional\/parrilla-para-horno-de-acero-inox-gn-1-1\/","og_locale":"es_ES","og_type":"article","og_title":"Parrilla para horno de acero inox gn 1\/1 - Officine Gullo","og_url":"https:\/\/officinegullo.com\/es\/accesorios\/accesorios-de-coccion-og-professional\/parrilla-para-horno-de-acero-inox-gn-1-1\/","og_site_name":"Officine Gullo","og_image":[{"width":500,"height":500,"url":"https:\/\/s3.eu-central-1.amazonaws.com\/eu.officinegullo.com\/wp-content\/uploads\/2021\/08\/20150528\/ACC043.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/officinegullo.com\/es\/accesorios\/accesorios-de-coccion-og-professional\/parrilla-para-horno-de-acero-inox-gn-1-1\/","url":"https:\/\/officinegullo.com\/es\/accesorios\/accesorios-de-coccion-og-professional\/parrilla-para-horno-de-acero-inox-gn-1-1\/","name":"Parrilla para horno de acero inox gn 1\/1 - Officine Gullo","isPartOf":{"@id":"https:\/\/officinegullo.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/officinegullo.com\/es\/accesorios\/accesorios-de-coccion-og-professional\/parrilla-para-horno-de-acero-inox-gn-1-1\/#primaryimage"},"image":{"@id":"https:\/\/officinegullo.com\/es\/accesorios\/accesorios-de-coccion-og-professional\/parrilla-para-horno-de-acero-inox-gn-1-1\/#primaryimage"},"thumbnailUrl":"https:\/\/s3.eu-central-1.amazonaws.com\/eu.officinegullo.com\/wp-content\/uploads\/2021\/08\/20150528\/ACC043.jpg","datePublished":"2021-09-17T13:08:25+00:00","breadcrumb":{"@id":"https:\/\/officinegullo.com\/es\/accesorios\/accesorios-de-coccion-og-professional\/parrilla-para-horno-de-acero-inox-gn-1-1\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/officinegullo.com\/es\/accesorios\/accesorios-de-coccion-og-professional\/parrilla-para-horno-de-acero-inox-gn-1-1\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/officinegullo.com\/es\/accesorios\/accesorios-de-coccion-og-professional\/parrilla-para-horno-de-acero-inox-gn-1-1\/#primaryimage","url":"https:\/\/s3.eu-central-1.amazonaws.com\/eu.officinegullo.com\/wp-content\/uploads\/2021\/08\/20150528\/ACC043.jpg","contentUrl":"https:\/\/s3.eu-central-1.amazonaws.com\/eu.officinegullo.com\/wp-content\/uploads\/2021\/08\/20150528\/ACC043.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/officinegullo.com\/es\/accesorios\/accesorios-de-coccion-og-professional\/parrilla-para-horno-de-acero-inox-gn-1-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/officinegullo.com\/es\/"},{"@type":"ListItem","position":2,"name":"Accesorios","item":"https:\/\/officinegullo.com\/es\/accesorios\/"},{"@type":"ListItem","position":3,"name":"Accesorios de cocci\u00f3n OG Professional","item":"https:\/\/officinegullo.com\/es\/accesorios\/accesorios-de-coccion-og-professional\/"},{"@type":"ListItem","position":4,"name":"Parrilla para horno de acero inox gn 1\/1"}]},{"@type":"WebSite","@id":"https:\/\/officinegullo.com\/es\/#website","url":"https:\/\/officinegullo.com\/es\/","name":"Officine Gullo","description":"The quintessential kitchen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/officinegullo.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/officinegullo.com\/es\/wp-json\/wp\/v2\/accessori\/12169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/officinegullo.com\/es\/wp-json\/wp\/v2\/accessori"}],"about":[{"href":"https:\/\/officinegullo.com\/es\/wp-json\/wp\/v2\/types\/accessori"}],"version-history":[{"count":0,"href":"https:\/\/officinegullo.com\/es\/wp-json\/wp\/v2\/accessori\/12169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/officinegullo.com\/es\/wp-json\/wp\/v2\/media\/5648"}],"wp:attachment":[{"href":"https:\/\/officinegullo.com\/es\/wp-json\/wp\/v2\/media?parent=12169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}